{"id":495,"date":"2019-10-22T12:11:22","date_gmt":"2019-10-22T10:11:22","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2019\/10\/19-edizione-della-settimana-della\/"},"modified":"2019-10-22T12:11:22","modified_gmt":"2019-10-22T10:11:22","slug":"19-edizione-della-settimana-della","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2019\/10\/19-edizione-della-settimana-della\/","title":{"rendered":"19\u00b0 EDIZIONE DELLA SETTIMANA DELLA LINGUA ITALIANA NEL MONDO"},"content":{"rendered":"<p>Dopo la Mostra su Leonardo da Vinci (in esposizione presso la casa Museo-Sharbatly sino al prossimo 15 novembre), il Consolato Generale d\u2019Italia ha portato un\u2019altra iniziativa culturale nella citt\u00e0 storica (Balad) di Gedda, lo scorso 21 ottobre. In cooperazione con il Ministero della Cultura Saudita e nell\u2019ambito delle manifestazioni dell\u2019intera rete diplomatica italiana per la 19\u00b0 edizione della Settimana della Lingua Italiana nel Mondo, abbiamo organizzato un concerto di opera lirica di un trio di giovani talenti italiani (il tenore Matteo Desole, la soprano Bianca Tognocchi e il maestro Andrea Solinas al piano), accompagnati dall\u2019attore Davide Marranchelli. L\u2019esibizione \u2013svoltasi nella suggestiva cornice della piazza accanto a Beit Nassif- ha presentato al pubblico saudita una antologia delle pi\u00f9 celebri \u201carie\u201d della lirica italiana (da Donizetti a Verdi, da Puccini a Mascagni), inframmezzate da spiegazioni sul linguaggio usato nell\u2019opera, ed \u00e8 stata molto apprezzata dal pubblico, buona parte del quale assisteva per la prima volta a una rappresentazione operistica. Si \u00e8 trattato di un momento \u201cstorico\u201d, visto che, per la prima volta a Gedda, \u00e8 stato autorizzato lo svolgimento di un concerto di musica occidentale all\u2019aperto, in un luogo pubblico, a dimostrazione del grande cambiamento culturale e sociale in atto nel Paese sotto la Vision 2030, che vede l\u2019Italia al primo posto nella partnership culturale.<\/p>\n","protected":false},"excerpt":{"rendered":"Dopo la Mostra su Leonardo da Vinci (in esposizione presso la casa Museo-Sharbatly sino al prossimo 15 novembre), il Consolato Generale d\u2019Italia ha portato un\u2019altra iniziativa culturale nella citt\u00e0 storica (Balad) di Gedda, lo scorso 21 ottobre. In cooperazione con il Ministero della Cultura Saudita e nell\u2019ambito delle manifestazioni dell\u2019intera rete diplomatica italiana per la [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-495","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/495\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}