{"id":483,"date":"2020-03-04T12:08:27","date_gmt":"2020-03-04T11:08:27","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2020\/03\/emergenza-nuovo-coronavirus-covid_0\/"},"modified":"2020-03-04T12:08:27","modified_gmt":"2020-03-04T11:08:27","slug":"emergenza-nuovo-coronavirus-covid_0","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2020\/03\/emergenza-nuovo-coronavirus-covid_0\/","title":{"rendered":"EMERGENZA NUOVO CORONAVIRUS (COVID-19)"},"content":{"rendered":"<p>Al fine di prevenire la diffusione del COVID-19 (nuovo coronavirus) nel Paese, le autorit\u00e0 locali hanno disposto su base temporanea le seguenti misure:<\/p>\n<p>\u00b7 Divieto di ingresso per compiere l\u2019Umrah e visitare la Moschea del Profeta a Medina (incluso il divieto per i cittadini dei Paesi del Consiglio di Cooperazione del Golfo di visitare Mecca e Medina senza una speciale autorizzazione);<\/p>\n<p>\u00b7 Divieto di ingresso per i passeggeri che sono stati in Cina, Taiwan, Hong Kong, Macao e Iran negli ultimi 14 giorni, anche se in transito o giunti con voli indiretti;<\/p>\n<p>\u00b7 Divieto di ingresso per i passeggeri con visto turistico da Paesi con casi confermati di coronavirus, inclusa l\u2019Italia (ovvero: Cina, Taiwan, Hong Kong, Iran, Italia, Corea del Sud, Macao, Giappone, Tailandia, Malesia, Indonesia, Pakistan, Afghanistan, Iraq, Filippine, Singapore, India, Libano, Siria, Yemen, Azerbaigian, Kazakhstan, Uzbekistan, Somalia e Vietnam). A tal fine, le autorit\u00e0 saudite hanno temporaneamente sospeso il rilascio di nuovi visti turistici e la validit\u00e0 di quelli gi\u00e0 rilasciati. Chi si trova gi\u00e0 in Arabia Saudita con visto turistico pu\u00f2 continuare il proprio soggiorno e lasciare il Paese senza problemi, nel rispetto dei limiti temporali di validit\u00e0 del visto. Non \u00e8 tuttavia permesso il rientro in Arabia Saudita, fino a nuove disposizioni.<\/p>\n<p>Non vi sono al momento specifiche restrizioni per chi \u00e8 in possesso di altre tipologie di visto o di regolare permesso di soggiorno. Anche alla luce di possibili repentini aggiornamenti delle disposizioni in vigore, si raccomanda di consultare previamente la compagnia aerea e, nel caso di voli indiretti dall\u2019Italia per l\u2019Arabia Saudita, di verificare anche le disposizioni in vigore nei Paesi di transito.<\/p>\n<p>Si segnala infine che le autorit\u00e0 locali hanno rafforzato i controlli sanitari aeroportuali. In particolare, sono stati attivati termoscanner per la misura della temperatura corporea. Nel caso in cui vengano rilevati sintomi compatibili con il COVID-19, le autorit\u00e0 sanitarie locali possono disporre l\u2019applicazione di ulteriori misure sanitarie di tutela. Ai passeggeri in arrivo da Paesi con casi confermati di coronavirus che, nei 14 giorni successivi all\u2019arrivo, presentino sintomi influenzali (febbre, mal di gola e difficolt\u00e0 respiratorie) \u00e8 fatta richiesta di contattare il numero dedicato all\u2019emergenza 937 e di rimanere a casa.<\/p>\n","protected":false},"excerpt":{"rendered":"Al fine di prevenire la diffusione del COVID-19 (nuovo coronavirus) nel Paese, le autorit\u00e0 locali hanno disposto su base temporanea le seguenti misure: \u00b7 Divieto di ingresso per compiere l\u2019Umrah e visitare la Moschea del Profeta a Medina (incluso il divieto per i cittadini dei Paesi del Consiglio di Cooperazione del Golfo di visitare Mecca [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-483","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=483"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/483\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=483"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}