{"id":477,"date":"2020-03-24T11:38:30","date_gmt":"2020-03-24T10:38:30","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2020\/03\/emergenza-covid-19-informazioni_0\/"},"modified":"2020-03-24T11:38:30","modified_gmt":"2020-03-24T10:38:30","slug":"emergenza-covid-19-informazioni_0","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2020\/03\/emergenza-covid-19-informazioni_0\/","title":{"rendered":"EMERGENZA COVID-19 INFORMAZIONI UTILI SULLE MISURE ADOTTATE DAL GOVERNO ITALIANO"},"content":{"rendered":"<p>A seguito dell&#8217;adozione del DPCM del 22 marzo scorso, dell&#8217;Ordinanza del Ministro della Salute 20 marzo 2020, dell&#8217;Ordinanza del 22 marzo 2020 adottata congiuntamente dal Ministro della Salute e dal Ministro dell&#8217;Interno, recante ulteriori misure in materia di contenimento e gestione dell&#8217;emergenza epidemiologica da COVID-19 sull&#8217;intero territorio nazionale, sono state predisposte una serie di domande&#038;risposte sull&#8217;applicazione della nuova normativa, al seguente link:<\/p>\n<p>\u00a0<a href=\"https:\/\/www.esteri.it\/mae\/it\/ministero\/normativaonline\/decreto-iorestoacasa-domande-frequenti\/focus-cittadini-italiani-in-rientro-dall-estero-e-cittadini-stranieri-in-italia.html\" title=\"testo\">https:\/\/www.esteri.it\/mae\/it\/ministero\/normativaonline\/decreto-iorestoacasa-domande-frequenti\/focus-cittadini-italiani-in-rientro-dall-estero-e-cittadini-stranieri-in-italia.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"A seguito dell&#8217;adozione del DPCM del 22 marzo scorso, dell&#8217;Ordinanza del Ministro della Salute 20 marzo 2020, dell&#8217;Ordinanza del 22 marzo 2020 adottata congiuntamente dal Ministro della Salute e dal Ministro dell&#8217;Interno, recante ulteriori misure in materia di contenimento e gestione dell&#8217;emergenza epidemiologica da COVID-19 sull&#8217;intero territorio nazionale, sono state predisposte una serie di domande&#038;risposte [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-477","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}