{"id":433,"date":"2020-11-18T14:35:36","date_gmt":"2020-11-18T13:35:36","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2020\/11\/italian-design-day-2020\/"},"modified":"2020-11-18T14:35:36","modified_gmt":"2020-11-18T13:35:36","slug":"italian-design-day-2020","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2020\/11\/italian-design-day-2020\/","title":{"rendered":"ITALIAN DESIGN DAY 2020"},"content":{"rendered":"<p>Il Consolato Generale d\u2019Italia a Gedda, in collaborazione con ArchiNet, ha ospitato il 16 novembre un seminario virtuale con l\u2019Architetto italiano <strong>Massimo Roj<\/strong> e l\u2019Architetto saudita <strong>Atef Alshehri<\/strong>, in occasione delle celebrazioni per la giornata internazionale del design italiano &#8211; <strong>Italian Design Day 2020<\/strong>. L\u2019evento, organizzato virtualmente a causa delle limitazioni imposte dal COVID, ha riscosso un notevole successo e suscitato grande interesse da parte della platea saudita che si \u00e8 intrattenuta per l\u2019intera durata del seminario, interloquendo attivamente con il noto Architetto italiano.<\/p>\n<p>Come noto, l<strong>\u2019Italian Design Day<\/strong> \u00e8 la rassegna tematica annuale lanciata nel 2017 dal Ministero per gli Affari Esteri e per la Cooperazione Internazionale, in collaborazione e con il sostegno del Ministero per i Beni e le Attivit\u00e0 Culturali e per il Turismo e delle principali associazioni di settore, con l\u2019obiettivo di promuovere il design italiano nel mondo. Negli ultimi decenni, l\u2019industria del design italiana si \u00e8 affermata quale uno dei principali motori della crescita economica e delle esportazioni italiane. Le aziende italiane di design si sono imposte sui mercati internazionali grazie alla loro capacit\u00e0 di produrre creazioni originali e rispondenti alle esigenze locali. Unendo eccellenza estetica, creativit\u00e0 e innovazione, il design italiano \u00e8 diventato un\u2019icona del \u201cmarchio Italia\u201d facilmente riconoscibile e apprezzata in tutto il mondo.<\/p>\n<p>Il tema dell\u2019edizione 2020 dell\u2019<strong>Italian Design Day<\/strong> \u00e8 stato \u201c<strong>Disegnare il futuro. Sviluppo, Innovazione, Sostenibilit\u00e0 e Bellezza<\/strong>\u201d. Seguendo la fortunata formula di \u201c100 Ambasciatori del design italiano per 100 citt\u00e0\u201d, cento professionisti (designers, architetti, urbanisti, imprenditori e insegnanti) hanno esplorato i diversi elementi del tema di quest\u2019anno in 100 eventi organizzati in tutto il mondo.<\/p>\n<p>Laureatosi al Politecnico di Milano nel 1986, l\u2019Architetto <strong>Massimo Roj<\/strong> dal 1982 lavora per diversi studi di architettura, tra cui Spinelli, Morisi e Helg e dal 1988 ricopre la carica di Project Architect e Project Manager per una societ\u00e0 internazionale di progettazione. Nel 1994 ha fondato a Milano Progetto CMR, societ\u00e0 italiana leader nel settore della progettazione integrata, dove svolge attivit\u00e0 nei campi della Pianificazione degli spazi, Disegno degli interni e Architettura. Dal 2000 ha iniziato ad esplorare nuovi mercati entrando a far parte di EAN, network europeo HOK e nel 2002 \u00e8 approdato in Cina, dove oggi vanta una posizione consolidata, con uffici a Pechino e Tianjin. Dal 2006 fa parte del comitato scientifico di ULI (Urban Land Institute). \u00c8 Visiting Professor all\u2019Universit\u00e0 di Tianjin. Tra gli altri, suoi sono il progetto delle Torri Garibaldi a Milano che riceve il Mattone d&#8217;Oro 2009 come Migliore Opera di Ristrutturazione ed il sistema di arredo Revo, disegnato per Manerba che si aggiudica il Good Design 2008 assegnato dal Chicago Athenaeum. Dal 2010 Progetto CMR \u00e8 tra i primi 100 studi di architettura al mondo segnalati da BD World Architecture 100.<\/p>\n<p>Fondata nel 2017 e con oltre 20mila membri in Arabia Saudita, Medio Oriente e nel resto del mondo, <strong>ArchiNet<\/strong> \u00e8 una piattaforma di dialogo che unisce professionisti e accademici rappresentativi di tutti i settori dell\u2019architettura e del design, con l\u2019obiettivo di favorire lo scambio di conoscenze e la condivisione di esperienze.<\/p>\n","protected":false},"excerpt":{"rendered":"Il Consolato Generale d\u2019Italia a Gedda, in collaborazione con ArchiNet, ha ospitato il 16 novembre un seminario virtuale con l\u2019Architetto italiano Massimo Roj e l\u2019Architetto saudita Atef Alshehri, in occasione delle celebrazioni per la giornata internazionale del design italiano &#8211; Italian Design Day 2020. L\u2019evento, organizzato virtualmente a causa delle limitazioni imposte dal COVID, ha [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-433","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=433"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/433\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=433"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}