{"id":429,"date":"2020-12-21T15:32:41","date_gmt":"2020-12-21T14:32:41","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2020\/12\/sospensione-temporanea-dei-voli\/"},"modified":"2020-12-21T15:32:41","modified_gmt":"2020-12-21T14:32:41","slug":"sospensione-temporanea-dei-voli","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2020\/12\/sospensione-temporanea-dei-voli\/","title":{"rendered":"SOSPENSIONE TEMPORANEA DEI VOLI INTERNAZIONALI DA E PER L&#8217;ARABIA SAUDITA"},"content":{"rendered":"<p>A seguito delle notizie sulla diffusione di una nuova variante di coronavirus, le Autorit\u00e0 saudite hanno deciso in via temporanea e con effetto immediato a partire dal <strong>21 dicembre la chiusura dei confini terrestri e marittimi e la sospensione di tutti i collegamenti aerei internazionali per una settimana,<\/strong> prorogabile di un\u2019ulteriore settimana. A chiunque sia rientrato in Arabia Saudita da uno dei Paesi europei o altri Paesi in cui \u00e8 stata identificata la nuova variante di coronavirus dopo l\u20198\/12\/2020 \u00e8 fatto obbligo di trascorrere un periodo di auto-isolamento di due settimane dalla data di arrivo nel Regno, sottoponendosi a test ogni cinque giorni. \u00c8 fatto obbligo di sottoporsi ad un test anche per chiunque sia rientrato negli ultimi tre mesi.<\/p>\n<p>L&#8217;Ambasciata d&#8217;Italia a Riad ed il Consolato Generale d&#8217;Italia a Gedda monitorano con attenzione la situazione, in contatto con le Autorita&#8217; locali, le Rappresentanze diplomatiche degli altri Paesi europei e la compagnia aerea Saudia Airlines ( l&#8217;unica ad operare voli diretti per l&#8217;Italia). Si avra&#8217; cura di informare tempestivamente circa eventuali decisioni da parte delle Autorita&#8217; saudite con riguardo alla ripresa dei collegamenti aerei internazionali.<\/p>\n<p>I cittadini italiani che si trovano temporaneamente in Arabia Saudita e che, nel rispetto delle disposizioni vigenti in Italia abbiano necessita&#8217; di lasciare l&#8217;Arabia Saudita per rientrare presso il proprio domicilio, possono segnalare eventuali situazioni di particolare necessita&#8217; mandando un email a <a href=\"mailto:anagrafe.gedda@esteri.it\">anagrafe.gedda@esteri.it<\/a> indicando nome, cognome, data di nascita, nazionalita&#8217; , nr. del passaporto, cellulare, tipo di visto, ente di appartenenza, localita&#8217;. Dovranno inoltre esprimere l&#8217;autorizzazione al trattamento e alla condivisione dei dati personali, come previsto dal Regolamento Generale sulla Protezione dei Dati UE2016\/679.<\/p>\n","protected":false},"excerpt":{"rendered":"A seguito delle notizie sulla diffusione di una nuova variante di coronavirus, le Autorit\u00e0 saudite hanno deciso in via temporanea e con effetto immediato a partire dal 21 dicembre la chiusura dei confini terrestri e marittimi e la sospensione di tutti i collegamenti aerei internazionali per una settimana, prorogabile di un\u2019ulteriore settimana. A chiunque sia [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-429","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/429\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=429"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}