{"id":427,"date":"2020-12-28T12:34:56","date_gmt":"2020-12-28T11:34:56","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2020\/12\/estensione-della-sospensione-dei\/"},"modified":"2020-12-28T12:34:56","modified_gmt":"2020-12-28T11:34:56","slug":"estensione-della-sospensione-dei","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2020\/12\/estensione-della-sospensione-dei\/","title":{"rendered":"ESTENSIONE DELLA SOSPENSIONE  DEI VOLI INTERNAZIONALI DA E PER L&#8217;ARABIA SAUDITA"},"content":{"rendered":"<p>AGGIORNAMENTO AL 28 DICEMBRE 2020: A seguito delle notizie sulla diffusione di una nuova variante di coronavirus, le Autorit\u00e0 saudite hanno deciso di prorogare per u<strong>n\u2019ulteriore settimana a partire dal 28 dicembre<\/strong> le misure gi\u00e0 in vigore riguardo la chiusura dei confini terrestri e marittimi e la sospensione dei collegamenti aerei internazionali. Mentre rimane in vigore il divieto generale di ingresso nel Regno, \u00e8 ora consentito agli stranieri di lasciare l\u2019Arabia Saudita e alle compagnie aeree di operare voli a tal fine. A chiunque sia rientrato in Arabia Saudita da uno dei Paesi europei o altri Paesi in cui \u00e8 stata identificata la nuova variante di coronavirus dopo l\u20198 dicembre 2020 \u00e8 fatto obbligo di trascorrere un periodo di auto-isolamento di due settimane dalla data di arrivo nel Regno, sottoponendosi a test ogni cinque giorni. \u00c8 fatto obbligo di sottoporsi ad un test anche per chiunque sia rientrato negli ultimi tre mesi.<\/p>\n","protected":false},"excerpt":{"rendered":"AGGIORNAMENTO AL 28 DICEMBRE 2020: A seguito delle notizie sulla diffusione di una nuova variante di coronavirus, le Autorit\u00e0 saudite hanno deciso di prorogare per un\u2019ulteriore settimana a partire dal 28 dicembre le misure gi\u00e0 in vigore riguardo la chiusura dei confini terrestri e marittimi e la sospensione dei collegamenti aerei internazionali. Mentre rimane in [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-427","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/427\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}