{"id":423,"date":"2021-02-03T14:00:13","date_gmt":"2021-02-03T13:00:13","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2021\/02\/nuove-misure-restrittive-adottate\/"},"modified":"2021-02-03T14:00:13","modified_gmt":"2021-02-03T13:00:13","slug":"nuove-misure-restrittive-adottate","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2021\/02\/nuove-misure-restrittive-adottate\/","title":{"rendered":"NUOVE MISURE RESTRITTIVE ADOTTATE DALLE AUTORIT\u00c0 SAUDITE."},"content":{"rendered":"<p>Nell\u2019ambito delle misure decise per prevenire la diffusione del Covid-19, le Autorit\u00e0 saudite hanno annunciato, a partire dalle ore <strong>21:00 (locali) di mercoled\u00ec 3 febbraio 2021<\/strong>, in via temporanea, il divieto di ingresso nel Regno per i passeggeri provenienti dai seguenti Paesi o che vi abbiano transitato nei 14 giorni precedenti: <strong>oltre all\u2019Italia,<\/strong> Argentina, Brasile, Egitto, Emirati Arabi Uniti, Francia, Giappone, Germania, India, Indonesia, Irlanda, Libano, Pakistan, Portogallo, Regno Unito, Stati Uniti, Sud Africa, Svezia, Svizzera e Turchia.<br \/>\u00c8 fatta eccezione solo per cittadini sauditi, diplomatici, operatori sanitari e loro familiari, il cui ingresso e\u2019 consentito nel rispetto delle misure precauzionali decise dal Ministero della Salute saudita (test PCR negativo prima dell\u2019ingresso e 14 giorni di quarantena all\u2019arrivo).<\/p>\n<p>Le Autorit\u00e0 saudite hanno inoltre annunciato che, in aggiunta alle misure precauzionali gi\u00e0 in vigore tra cui l\u2019obbligo di indossare la mascherina in pubblico, a partire dalle ore 22:00 (locali) di gioved\u00ec 4 febbraio 2021, saranno in vigore le seguenti misure preventive:<\/p>\n<p>Sospensione di tutti gli eventi ed incontri conviviali, inclusi matrimoni, riunioni di lavoro e simili assembramenti in strutture pubbliche e private utilizzate per questi fini (misura in vigore per 30 giorni \u2013 estendibili);Limite di 20 persone per ogni eventuale raggruppamento (10 giorni &#8211; estendibili);Sospensione di ogni attivit\u00e0 di intrattenimento e chiusura di cinema e strutture ludiche o sportive situati in centri commerciali o altrove (10 giorni &#8211; estendibili);Sospensione di servizi di ristorazione e bar, fatto salvo per le richieste di consegna a domicilio (10 giorni &#8211; estendibili).<\/p>\n<p>Nell\u2019attuazione di queste misure, le Autorit\u00e0 competenti saudite intensificheranno gli sforzi di monitoraggio, verifica e sanzione delle violazioni. Si raccomanda ai connazionali di prestare massima attenzione al rispetto di queste misure, anche in considerazione delle multe elevate previste.<\/p>\n<p><strong>Indicazioni ai connazionali<\/strong><\/p>\n<p>L\u2019Ambasciata d\u2019Italia a Riad e il Consolato Generale a Gedda monitorano con attenzione la situazione, in contatto con le Autorit\u00e0 locali e le rappresentanze diplomatiche degli altri Paesi europei. Si avr\u00e0 cura di informare tempestivamente circa eventuali decisioni da parte delle Autorit\u00e0 locali con riguardo alla revoca delle restrizioni all\u2019ingresso in Arabia Saudita di cui sopra.<\/p>\n<p>I cittadini italiani possono segnalare eventuali situazioni di particolare necessit\u00e0 mandando un\u2019email a riad.consolare@esteri.it o anagrafe.gedda@esteri.it (secondo la circoscrizione consolare competente a livello territoriale), indicando nome, cognome, data di nascita, nr. di passaporto, cellulare, tipo di visto, ente di appartenenza, localit\u00e0. Dovranno inoltre esprimere l\u2019autorizzazione al trattamento e alla condivisione dei dati personali, come previsto dal Regolamento Generale sulla Protezione dei Dati UE 2016\/679.<\/p>\n<p>Si invitano tutti i connazionali al rispetto delle misure personali di natura igienico-sanitaria utili a prevenire il contagio da coronavirus, raccomandate dalle Autorit\u00e0 sanitarie italiane e saudite.<\/p>\n<p>In caso di sintomi influenzali sospetti (febbre, mal di gola e difficolt\u00e0 respiratorie), si raccomanda di consultare il proprio medico di fiducia o chiamare il numero 937 per indicazioni su come procedere, avendo cura di evitare contatti personali per ridurre il rischio di diffusione del virus.<\/p>\n<p>Si invitano i connazionali a prestare massima attenzione alla verifica della validit\u00e0 del proprio visto o permesso di soggiorno.<\/p>\n<p>Si ricorda che, in linea generale, per qualsiasi problematica relativa ai visti in entrata e in uscita, \u00e8 obbligatorio rivolgersi al proprio sponsor per l\u2019assistenza e le autorizzazioni necessarie. Infatti, in Arabia Saudita, lo sponsor (che pu\u00f2 essere persona fisica o giuridica), \u00e8 l\u2019unico responsabile della permanenza del lavoratore\/visitatore straniero nei confronti delle Autorit\u00e0 locali.<\/p>\n<p><strong>Situazione epidemiologica in Arabia Saudita<\/strong><\/p>\n<p>Per aggiornamenti ed informazioni ufficiali sulla situazione epidemiologica in Arabia Saudita, si rimanda al sito internet e ai canali social del Ministero della Salute saudita e dell\u2019Agenzia stampa ufficiale (Saudi Press Agency \u2013 <a href=\"https:\/\/www.spa.gov.sa\/home.php?lang=en)\">https:\/\/www.spa.gov.sa\/home.php?lang=en)<\/a>, oltre che al sito internet dedicato: <a href=\"https:\/\/covid19.cdc.gov.sa\">https:\/\/covid19.cdc.gov.sa<\/a>e alle principali testate e canali televisivi nazionali.<\/p>\n<p><strong>Informazioni e contatti utili<\/strong><\/p>\n<p>Per assistenza consolare, il Consolato \u00e8 raggiungibile attraverso l\u2019e-mail: anagrafe.gedda@esteri.it o chiamando il numero di cellulare del Funzionario di Turno attivo h24: 00966 50 667 8310.<\/p>\n<p>Per informazioni sulle misure adottate dalle Autorit\u00e0 italiane nei confronti dei cittadini italiani in rientro dall\u2019estero e cittadini stranieri in Italia, si rimanda alla pagina dedicata sul sito del Ministero degli Affari Esteri e della Cooperazione Internazionale: <a href=\"https:\/\/www.esteri.it\/mae\/it\/ministero\/normativaonline\/decreto-iorestoacasa-domande-frequenti\/focus-cittadini-italiani-in-rientro-dall-estero-e-cittadini-stranieri-in-italia.html\">Focus: Cittadini Italiani in rientro dall\u2019estero e cittadini stranieri in Italia.<\/a><\/p>\n<p>Ulteriori informazioni aggiornate in tempo reale sono disponibili sul sito \u201c<a href=\"http:\/\/www.viaggiaresicuri.it\/approfondimenti-insights\/saluteinviaggio\">Viaggiare Sicuri<\/a>\u201d della Farnesina.<\/p>\n","protected":false},"excerpt":{"rendered":"Nell\u2019ambito delle misure decise per prevenire la diffusione del Covid-19, le Autorit\u00e0 saudite hanno annunciato, a partire dalle ore 21:00 (locali) di mercoled\u00ec 3 febbraio 2021, in via temporanea, il divieto di ingresso nel Regno per i passeggeri provenienti dai seguenti Paesi o che vi abbiano transitato nei 14 giorni precedenti: oltre all\u2019Italia, Argentina, Brasile, [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-423","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=423"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/423\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=423"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}