{"id":414,"date":"2021-05-30T10:28:07","date_gmt":"2021-05-30T08:28:07","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2021\/05\/covid-19-focus-sulle-misure-adottate_0\/"},"modified":"2021-05-30T10:28:07","modified_gmt":"2021-05-30T08:28:07","slug":"covid-19-focus-sulle-misure-adottate_0","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2021\/05\/covid-19-focus-sulle-misure-adottate_0\/","title":{"rendered":"COVID-19. FOCUS SULLE MISURE ADOTTATE DALLE AUTORIT\u00c0 SAUDITE E INDICAZIONI AI CONNAZIONALI."},"content":{"rendered":"<p>Nell\u2019ambito delle misure decise per prevenire la diffusione del Covid-19, le Autorit\u00e0 saudite hanno annunciato, a partire dal 3 febbraio 2021, in via temporanea, il divieto di ingresso nel Regno per i passeggeri provenienti dai seguenti 20 Paesi o che vi abbiano transitato nei 14 giorni precedenti: oltre all\u2019Italia, Argentina, Brasile, Egitto, Emirati Arabi Uniti, Francia, Giappone, Germania, India, Indonesia, Irlanda, Libano, Pakistan, Portogallo, Regno Unito, Stati Uniti, Sud Africa, Svezia, Svizzera e Turchia.<\/p>\n<p>D<strong>al 30 maggio 2021 le Autorit\u00e0 saudite hanno abrogato il divieto di ingresso per i passeggeri provenienti da 11 Stati: oltre all\u2019Italia<\/strong>, Emirati Arabi Uniti, Stati Uniti, Svezia, Svizzera, Portogallo, Regno Unito, Germania, Francia, Irlanda, Giappone.<\/p>\n<p>Per i passeggeri internazionali autorizzati all\u2019ingresso , occorre conformarsi alle seguenti misure precauzionali, aggiornate da ultimo lo scorso 10 maggio 2021 e entrate in vigore il 20 maggio 2021:<\/p>\n<p>&#8211; certificato di PCR test negativo eseguito nelle 72 ore precedenti l\u2019imbarco sul volo. La misura si applica a tutti i passeggeri di et\u00e0 pari o superiore agli 8 anni.<\/p>\n<p>&#8211; quarantena obbligatoria di sette giorni a partire dall\u2019ingresso sul territorio saudita per i non vaccinati da svolgere presso la citt\u00e0 di arrivo; l\u2019Autorit\u00e0 per l\u2019aviazione civile saudita ha istruito le compagnie aeree di includere nel prezzo del biglietto aereo il costo per trascorrere il periodo di quarantena in una delle apposite strutture alberghiere indicate dal Ministero del Turismo saudita, nonch\u00e9 il costo dell\u2019assicurazione sanitaria per l\u2019eventualit\u00e0 di contagio; al termine del periodo di isolamento, occorrer\u00e0 effettuare un nuovo esame PCR. In caso di esito negativo, l\u2019isolamento potr\u00e0 essere interrotto l\u20198\u00b0 giorno.<\/p>\n<p>Le misure sopra descritte non si applicano alle seguenti categorie di viaggiatori:<\/p>\n<p>\u2022 persone considerate \u201cimmunizzate\u201d;<br \/>\u2022 titolari di visto diplomatico non immunizzati che devono, da parte loro, rispettare un periodo di autoisolamento domiciliare ed eseguire un test PCR il 6 \u00b0 giorno;<br \/>\u2022 il coniuge, i figli e il personale domestico di cittadini sauditi che devono, da parte loro, rispettare un periodo di isolamento domiciliare di 7 giorni ed eseguire un test PCR il 6 \u00b0 giorno;<br \/>\u2022 personale domestico che accompagna un residente immunizzato;<br \/>\u2022 personale navigante;<br \/>\u2022 operatori sanitari.<\/p>\n<p>Le Autorit\u00e0 saudite considerano immunizzate le seguenti categorie di persone:<\/p>\n<p>Per cittadini o residenti:<\/p>\n<p>\u2022 coloro il cui stato nell\u2019APP Tawaklna indica l\u2019immunit\u00e0,<br \/>\u2022 coloro che hanno completato le vaccinazioni contro COVID-19,<br \/>\u2022 coloro che hanno ricevuto la prima dose di uno dei vaccini almeno 14 giorni prima dell\u2019arrivo nel Regno,<br \/>\u2022 coloro che sono guariti da COVID-19 contratto non pi\u00f9 di 6 mesi prima dell\u2019arrivo nel Paese.<\/p>\n<p>Per non-residenti e visitatori per la prima volta:<br \/>Solo coloro che hanno ricevuto da almeno 14 giorni entrambe le dosi (per i vaccini che prevedono il richiamo) e di una dose per il vaccino J&#038;J, a condizione che si tratti di vaccini autorizzati dal Regno dell&#8217;Arabia Saudita e dietro presentazione di un certificato vaccinale o una prova in conformit\u00e0 con i requisiti stabiliti dal Ministero della Salute saudita.<\/p>\n<p><strong>Indicazioni ai connazionali<\/strong><\/p>\n<p>L\u2019Ambasciata d\u2019Italia a Riad e il Consolato Generale a Gedda monitorano con attenzione la situazione, in contatto con le Autorit\u00e0 locali e le rappresentanze diplomatiche degli altri Paesi europei. Si avr\u00e0 cura di informare tempestivamente circa eventuali decisioni da parte delle Autorit\u00e0 locali con riguardo alla revoca delle restrizioni all\u2019ingresso in Arabia Saudita di cui sopra.<\/p>\n<p>I cittadini italiani possono segnalare eventuali situazioni di particolare necessit\u00e0 mandando un\u2019email a <a href=\"mailto:riad.consolare@esteri.it\">riad.consolare@esteri.it<\/a> o <a href=\"mailto:anagrafe.gedda@esteri.it\">anagrafe.gedda@esteri.it<\/a> (secondo la circoscrizione consolare competente a livello territoriale), indicando nome, cognome, data di nascita, nr. di passaporto, cellulare, tipo di visto, ente di appartenenza, localit\u00e0. Dovranno inoltre esprimere l\u2019autorizzazione al trattamento e alla condivisione dei dati personali, come previsto dal Regolamento Generale sulla Protezione dei Dati UE 2016\/679.<\/p>\n<p>Si invitano tutti i connazionali al rispetto delle misure personali di natura igienico-sanitaria utili a prevenire il contagio da coronavirus, raccomandate dalle Autorit\u00e0 sanitarie italiane e saudite.<\/p>\n<p>In caso di sintomi influenzali sospetti (febbre, mal di gola e difficolt\u00e0 respiratorie), si raccomanda di consultare il proprio medico di fiducia o chiamare il numero 937 per indicazioni su come procedere, avendo cura di evitare contatti personali per ridurre il rischio di diffusione del virus.<\/p>\n<p>Si invitano i connazionali a prestare massima attenzione alla verifica della validit\u00e0 del proprio visto o permesso di soggiorno.<\/p>\n<p>Si ricorda che, in linea generale, per qualsiasi problematica relativa ai visti in entrata e in uscita, \u00e8 obbligatorio rivolgersi al proprio sponsor per l\u2019assistenza e le autorizzazioni necessarie. Infatti, in Arabia Saudita, lo sponsor (che pu\u00f2 essere persona fisica o giuridica), \u00e8 l\u2019unico responsabile della permanenza del lavoratore\/visitatore straniero nei confronti delle Autorit\u00e0 locali.<\/p>\n<p><strong>Situazione epidemiologica in Arabia Saudita<\/strong><\/p>\n<p>Per aggiornamenti ed informazioni ufficiali sulla situazione epidemiologica in Arabia Saudita, si rimanda al sito internet e ai canali social del Ministero della Salute saudita e dell\u2019Agenzia stampa ufficiale (Saudi Press Agency \u2013 <a href=\"https:\/\/www.spa.gov.sa\/home.php?lang=en)\">https:\/\/www.spa.gov.sa\/home.php?lang=en)<\/a>, oltre che al sito internet dedicato: <a href=\"https:\/\/covid19.cdc.gov.sa\">https:\/\/covid19.cdc.gov.sa<\/a> e alle principali testate e canali televisivi nazionali.<\/p>\n<p><strong>Informazioni e contatti utili<\/strong><\/p>\n<p>Per assistenza consolare, il Consolato \u00e8 raggiungibile attraverso l\u2019e-mail: <a href=\"mailto:anagrafe.gedda@esteri.it\">anagrafe.gedda@esteri.it<\/a> o chiamando il numero di cellulare del Funzionario di Turno attivo h24: 00966 506 678310.<\/p>\n<p>Per informazioni sulle misure adottate dalle Autorit\u00e0 italiane nei confronti dei cittadini italiani in rientro dall\u2019estero e cittadini stranieri in Italia, si rimanda alla pagina dedicata sul sito del Ministero degli Affari Esteri e della Cooperazione Internazionale: Focus: Cittadini Italiani in rientro dall\u2019estero e cittadini stranieri in Italia.<\/p>\n<p>Ulteriori informazioni aggiornate in tempo reale sono disponibili sul sito \u201cViaggiare Sicuri\u201d della Farnesina.<\/p>\n<p>(Aggiornato al 30 maggio 2021)<\/p>\n","protected":false},"excerpt":{"rendered":"Nell\u2019ambito delle misure decise per prevenire la diffusione del Covid-19, le Autorit\u00e0 saudite hanno annunciato, a partire dal 3 febbraio 2021, in via temporanea, il divieto di ingresso nel Regno per i passeggeri provenienti dai seguenti 20 Paesi o che vi abbiano transitato nei 14 giorni precedenti: oltre all\u2019Italia, Argentina, Brasile, Egitto, Emirati Arabi Uniti, [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-414","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=414"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/414\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=414"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}