{"id":368,"date":"2022-08-28T08:49:30","date_gmt":"2022-08-28T06:49:30","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2022\/08\/elezioni-politiche-2022\/"},"modified":"2022-08-28T08:49:30","modified_gmt":"2022-08-28T06:49:30","slug":"elezioni-politiche-2022","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2022\/08\/elezioni-politiche-2022\/","title":{"rendered":"ELEZIONI POLITICHE 2022"},"content":{"rendered":"<p>Gli elettori iscritti AIRE riceveranno il plico elettorale al proprio indirizzo di residenza con le istruzioni per restituirlo al Consolato Gli elettori temporaneamente all\u2019estero che ne hanno fatto richiesta riceveranno il plico all\u2019indirizzo comunicato.<\/p>\n","protected":false},"excerpt":{"rendered":"Gli elettori iscritti AIRE riceveranno il plico elettorale al proprio indirizzo di residenza con le istruzioni per restituirlo al Consolato Gli elettori temporaneamente all\u2019estero che ne hanno fatto richiesta riceveranno il plico all\u2019indirizzo comunicato.","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-368","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}