{"id":361,"date":"2022-09-11T12:04:35","date_gmt":"2022-09-11T10:04:35","guid":{"rendered":"https:\/\/consgedda.esteri.it\/news\/dal_consolato\/2022\/09\/elezioni-politiche-2022-avviso_1\/"},"modified":"2022-09-11T12:04:35","modified_gmt":"2022-09-11T10:04:35","slug":"elezioni-politiche-2022-avviso_1","status":"publish","type":"post","link":"https:\/\/consgedda.esteri.it\/it\/news\/dal_consolato\/2022\/09\/elezioni-politiche-2022-avviso_1\/","title":{"rendered":"ELEZIONI POLITICHE 2022. AVVISO AI CONNAZIONALI"},"content":{"rendered":"<p>Si informano i connazionali che, al fine di facilitare le eventuali richieste di duplicato del plico elettorale, <strong>il Consolato Generale sara&#8217; aperto venerdi&#8217; e sabato prossimi<\/strong> ( 16 e 17 settembre), dalle <strong>ore 9:30 alle ore 13:30<\/strong>.<\/p>\n<p>La richiesta \u2013 che pu\u00f2 essere redatta utilizzando il modello disponibile in allegato a questa pagina \u2013 dovr\u00e0 essere accompagnata da un valido documento di riconoscimento.<\/p>\n<p>Gli elettori che richiederanno il duplicato del plico elettorale dovranno dichiarare di essere consapevoli delle responsabilit\u00e0 penali conseguenti al doppio voto, previste dall\u2019art. 18, comma 2, della Legge 459\/2001, secondo il quale: \u201cChiunque, in occasione delle elezioni delle Camere e dei referendum, vota sia per corrispondenza che nel seggio di ultima iscrizione in Italia, ovvero vota pi\u00f9 volte per corrispondenza \u00e8 punito con la reclusione da uno a tre anni e con la multa da 52 euro a 258 euro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Si informano i connazionali che, al fine di facilitare le eventuali richieste di duplicato del plico elettorale, il Consolato Generale sara&#8217; aperto venerdi&#8217; e sabato prossimi ( 16 e 17 settembre), dalle ore 9:30 alle ore 13:30. La richiesta \u2013 che pu\u00f2 essere redatta utilizzando il modello disponibile in allegato a questa pagina \u2013 dovr\u00e0 [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-361","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":0,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/posts\/361\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgedda.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}